{"id":814,"count":1,"description":"","link":"https:\/\/truckonline.de\/blog\/tag\/malteser\/","name":"Malteser","slug":"malteser","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Malteser Archive | TruckOnline.de<\/title>\n<meta name=\"description\" content=\"TruckOnline.de ist das gr\u00f6\u00dfte deutschsprachige Weblog zum Thema Transport &amp; Verkehr. Gegr\u00fcndet wurde es im Februar 2008. Seitdem wurden \u00fcber 6 000 Beitr\u00e4ge geschrieben sowie \u00fcber 30 000 Kommentare von den Lesern und Leserinnen hinterlassen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/truckonline.de\/blog\/tag\/malteser\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Malteser Archive | TruckOnline.de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/truckonline.de\/blog\/tag\/malteser\/\" \/>\n<meta property=\"og:site_name\" content=\"TruckOnline.de\" \/>\n<meta property=\"og:image\" content=\"https:\/\/truckonline.de\/blog\/wp-content\/uploads\/2019\/12\/IMG_20191229_225424-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@truckblog\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/tag\\\/malteser\\\/\",\"url\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/tag\\\/malteser\\\/\",\"name\":\"Malteser Archive | TruckOnline.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/#website\"},\"description\":\"TruckOnline.de ist das gr\u00f6\u00dfte deutschsprachige Weblog zum Thema Transport & Verkehr. Gegr\u00fcndet wurde es im Februar 2008. Seitdem wurden \u00fcber 6 000 Beitr\u00e4ge geschrieben sowie \u00fcber 30 000 Kommentare von den Lesern und Leserinnen hinterlassen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/tag\\\/malteser\\\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/tag\\\/malteser\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Malteser\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/\",\"name\":\"TruckOnline.de\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/#\\\/schema\\\/person\\\/4cb59b86ffde81f882f56439688fda19\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/#\\\/schema\\\/person\\\/4cb59b86ffde81f882f56439688fda19\",\"name\":\"maik\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/logoinnenweiss.png\",\"url\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/logoinnenweiss.png\",\"contentUrl\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/logoinnenweiss.png\",\"width\":733,\"height\":125,\"caption\":\"maik\"},\"logo\":{\"@id\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/logoinnenweiss.png\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/truckblog\",\"https:\\\/\\\/www.instagram.com\\\/truck_online\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/truckblog\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/truckonline\",\"https:\\\/\\\/www.tumblr.com\\\/truckonline\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Malteser Archive | TruckOnline.de","description":"TruckOnline.de ist das gr\u00f6\u00dfte deutschsprachige Weblog zum Thema Transport & Verkehr. Gegr\u00fcndet wurde es im Februar 2008. Seitdem wurden \u00fcber 6 000 Beitr\u00e4ge geschrieben sowie \u00fcber 30 000 Kommentare von den Lesern und Leserinnen hinterlassen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/truckonline.de\/blog\/tag\/malteser\/","og_locale":"de_DE","og_type":"article","og_title":"Malteser Archive | TruckOnline.de","og_url":"https:\/\/truckonline.de\/blog\/tag\/malteser\/","og_site_name":"TruckOnline.de","og_image":[{"width":2560,"height":1920,"url":"https:\/\/truckonline.de\/blog\/wp-content\/uploads\/2019\/12\/IMG_20191229_225424-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@truckblog","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/truckonline.de\/blog\/tag\/malteser\/","url":"https:\/\/truckonline.de\/blog\/tag\/malteser\/","name":"Malteser Archive | TruckOnline.de","isPartOf":{"@id":"https:\/\/truckonline.de\/blog\/#website"},"description":"TruckOnline.de ist das gr\u00f6\u00dfte deutschsprachige Weblog zum Thema Transport & Verkehr. Gegr\u00fcndet wurde es im Februar 2008. Seitdem wurden \u00fcber 6 000 Beitr\u00e4ge geschrieben sowie \u00fcber 30 000 Kommentare von den Lesern und Leserinnen hinterlassen.","breadcrumb":{"@id":"https:\/\/truckonline.de\/blog\/tag\/malteser\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/truckonline.de\/blog\/tag\/malteser\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/truckonline.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Malteser"}]},{"@type":"WebSite","@id":"https:\/\/truckonline.de\/blog\/#website","url":"https:\/\/truckonline.de\/blog\/","name":"TruckOnline.de","description":"","publisher":{"@id":"https:\/\/truckonline.de\/blog\/#\/schema\/person\/4cb59b86ffde81f882f56439688fda19"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/truckonline.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/truckonline.de\/blog\/#\/schema\/person\/4cb59b86ffde81f882f56439688fda19","name":"maik","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/truckonline.de\/blog\/wp-content\/uploads\/2019\/12\/logoinnenweiss.png","url":"https:\/\/truckonline.de\/blog\/wp-content\/uploads\/2019\/12\/logoinnenweiss.png","contentUrl":"https:\/\/truckonline.de\/blog\/wp-content\/uploads\/2019\/12\/logoinnenweiss.png","width":733,"height":125,"caption":"maik"},"logo":{"@id":"https:\/\/truckonline.de\/blog\/wp-content\/uploads\/2019\/12\/logoinnenweiss.png"},"sameAs":["https:\/\/www.facebook.com\/truckblog","https:\/\/www.instagram.com\/truck_online\/","https:\/\/x.com\/https:\/\/twitter.com\/truckblog","https:\/\/www.youtube.com\/user\/truckonline","https:\/\/www.tumblr.com\/truckonline"]}]}},"_links":{"self":[{"href":"https:\/\/truckonline.de\/blog\/wp-json\/wp\/v2\/tags\/814","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/truckonline.de\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/truckonline.de\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/truckonline.de\/blog\/wp-json\/wp\/v2\/posts?tags=814"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}