{"id":923,"date":"2009-08-26T18:33:27","date_gmt":"2009-08-26T17:33:27","guid":{"rendered":"https:\/\/truckonline.de\/blog\/?p=923"},"modified":"2009-08-26T18:33:27","modified_gmt":"2009-08-26T17:33:27","slug":"spesenurteil","status":"publish","type":"post","link":"https:\/\/truckonline.de\/blog\/2009\/08\/26\/spesenurteil\/","title":{"rendered":"Spesenurteil"},"content":{"rendered":"<p>Der Fiskus darf Pauschalen f\u00fcr Kost und Logis nicht dem steuerpflichtigen Zusatzlohn zurechnen, wenn tats\u00e4chlich Kosten in der entsprechenden Gr\u00f6\u00dfenordnung angefallen sind.<br \/>\nDas entschied das Finanzgericht Kassel und gab damit einem Lkw &#8211; Fahrer recht, der belegen konnte, nicht wie vom Finanzamt vermutet, in seinem Lkw \u00fcbernachtet zu haben.<\/p>\n<p>Az.: 11 K 1498\/05<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der Fiskus darf Pauschalen f\u00fcr Kost und Logis nicht dem steuerpflichtigen Zusatzlohn zurechnen, wenn tats\u00e4chlich Kosten in der entsprechenden Gr\u00f6\u00dfenordnung angefallen sind. Das entschied das&#8230;<\/p>\n<div class=\"more-link-wrapper\"><a class=\"more-link\" href=\"https:\/\/truckonline.de\/blog\/2009\/08\/26\/spesenurteil\/\">Sie haben Ihr Ziel fast erreicht.<span class=\"screen-reader-text\">Spesenurteil<\/span><\/a><\/div>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"iawp_total_views":1,"_metis_text_type":"","_metis_text_length":0,"_post_count":0,"footnotes":""},"categories":[1],"tags":[331,928,562],"class_list":["post-923","post","type-post","status-publish","format-standard","hentry","category-allgemeines","tag-gericht","tag-spesen","tag-urteil","ratio-2-1","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Spesenurteil | TruckOnline.de<\/title>\n<meta name=\"description\" content=\"Der Fiskus darf Pauschalen f\u00fcr Kost und Logis nicht dem steuerpflichtigen Zusatzlohn zurechnen, wenn tats\u00e4chlich Kosten in der entsprechenden\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/truckonline.de\/blog\/2009\/08\/26\/spesenurteil\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Spesenurteil | TruckOnline.de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/truckonline.de\/blog\/2009\/08\/26\/spesenurteil\/\" \/>\n<meta property=\"og:site_name\" content=\"TruckOnline.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/truckblog\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/truckblog\" \/>\n<meta property=\"article:published_time\" content=\"2009-08-26T17:33:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/truckonline.de\/blog\/wp-content\/uploads\/2019\/12\/IMG_20191229_225424-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"maik\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/truckblog\" \/>\n<meta name=\"twitter:site\" content=\"@truckblog\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"maik\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/2009\\\/08\\\/26\\\/spesenurteil\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/2009\\\/08\\\/26\\\/spesenurteil\\\/\"},\"author\":{\"name\":\"maik\",\"@id\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/#\\\/schema\\\/person\\\/4cb59b86ffde81f882f56439688fda19\"},\"headline\":\"Spesenurteil\",\"datePublished\":\"2009-08-26T17:33:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/2009\\\/08\\\/26\\\/spesenurteil\\\/\"},\"wordCount\":55,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/#\\\/schema\\\/person\\\/4cb59b86ffde81f882f56439688fda19\"},\"keywords\":[\"Gericht\",\"Spesen\",\"Urteil\"],\"articleSection\":[\"Allgemeines\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/truckonline.de\\\/blog\\\/2009\\\/08\\\/26\\\/spesenurteil\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/2009\\\/08\\\/26\\\/spesenurteil\\\/\",\"url\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/2009\\\/08\\\/26\\\/spesenurteil\\\/\",\"name\":\"Spesenurteil | TruckOnline.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/#website\"},\"datePublished\":\"2009-08-26T17:33:27+00:00\",\"description\":\"Der Fiskus darf Pauschalen f\u00fcr Kost und Logis nicht dem steuerpflichtigen Zusatzlohn zurechnen, wenn tats\u00e4chlich Kosten in der entsprechenden\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/2009\\\/08\\\/26\\\/spesenurteil\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/truckonline.de\\\/blog\\\/2009\\\/08\\\/26\\\/spesenurteil\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/2009\\\/08\\\/26\\\/spesenurteil\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Spesenurteil\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/\",\"name\":\"TruckOnline.de\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/#\\\/schema\\\/person\\\/4cb59b86ffde81f882f56439688fda19\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/#\\\/schema\\\/person\\\/4cb59b86ffde81f882f56439688fda19\",\"name\":\"maik\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/logoinnenweiss.png\",\"url\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/logoinnenweiss.png\",\"contentUrl\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/logoinnenweiss.png\",\"width\":733,\"height\":125,\"caption\":\"maik\"},\"logo\":{\"@id\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/logoinnenweiss.png\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/truckblog\",\"https:\\\/\\\/www.instagram.com\\\/truck_online\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/truckblog\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/truckonline\",\"https:\\\/\\\/www.tumblr.com\\\/truckonline\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Spesenurteil | TruckOnline.de","description":"Der Fiskus darf Pauschalen f\u00fcr Kost und Logis nicht dem steuerpflichtigen Zusatzlohn zurechnen, wenn tats\u00e4chlich Kosten in der entsprechenden","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/truckonline.de\/blog\/2009\/08\/26\/spesenurteil\/","og_locale":"de_DE","og_type":"article","og_title":"Spesenurteil | TruckOnline.de","og_url":"https:\/\/truckonline.de\/blog\/2009\/08\/26\/spesenurteil\/","og_site_name":"TruckOnline.de","article_publisher":"https:\/\/www.facebook.com\/truckblog","article_author":"https:\/\/www.facebook.com\/truckblog","article_published_time":"2009-08-26T17:33:27+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/truckonline.de\/blog\/wp-content\/uploads\/2019\/12\/IMG_20191229_225424-scaled.jpg","type":"image\/jpeg"}],"author":"maik","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/truckblog","twitter_site":"@truckblog","twitter_misc":{"Verfasst von":"maik"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/truckonline.de\/blog\/2009\/08\/26\/spesenurteil\/#article","isPartOf":{"@id":"https:\/\/truckonline.de\/blog\/2009\/08\/26\/spesenurteil\/"},"author":{"name":"maik","@id":"https:\/\/truckonline.de\/blog\/#\/schema\/person\/4cb59b86ffde81f882f56439688fda19"},"headline":"Spesenurteil","datePublished":"2009-08-26T17:33:27+00:00","mainEntityOfPage":{"@id":"https:\/\/truckonline.de\/blog\/2009\/08\/26\/spesenurteil\/"},"wordCount":55,"commentCount":0,"publisher":{"@id":"https:\/\/truckonline.de\/blog\/#\/schema\/person\/4cb59b86ffde81f882f56439688fda19"},"keywords":["Gericht","Spesen","Urteil"],"articleSection":["Allgemeines"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/truckonline.de\/blog\/2009\/08\/26\/spesenurteil\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/truckonline.de\/blog\/2009\/08\/26\/spesenurteil\/","url":"https:\/\/truckonline.de\/blog\/2009\/08\/26\/spesenurteil\/","name":"Spesenurteil | TruckOnline.de","isPartOf":{"@id":"https:\/\/truckonline.de\/blog\/#website"},"datePublished":"2009-08-26T17:33:27+00:00","description":"Der Fiskus darf Pauschalen f\u00fcr Kost und Logis nicht dem steuerpflichtigen Zusatzlohn zurechnen, wenn tats\u00e4chlich Kosten in der entsprechenden","breadcrumb":{"@id":"https:\/\/truckonline.de\/blog\/2009\/08\/26\/spesenurteil\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/truckonline.de\/blog\/2009\/08\/26\/spesenurteil\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/truckonline.de\/blog\/2009\/08\/26\/spesenurteil\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/truckonline.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Spesenurteil"}]},{"@type":"WebSite","@id":"https:\/\/truckonline.de\/blog\/#website","url":"https:\/\/truckonline.de\/blog\/","name":"TruckOnline.de","description":"","publisher":{"@id":"https:\/\/truckonline.de\/blog\/#\/schema\/person\/4cb59b86ffde81f882f56439688fda19"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/truckonline.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/truckonline.de\/blog\/#\/schema\/person\/4cb59b86ffde81f882f56439688fda19","name":"maik","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/truckonline.de\/blog\/wp-content\/uploads\/2019\/12\/logoinnenweiss.png","url":"https:\/\/truckonline.de\/blog\/wp-content\/uploads\/2019\/12\/logoinnenweiss.png","contentUrl":"https:\/\/truckonline.de\/blog\/wp-content\/uploads\/2019\/12\/logoinnenweiss.png","width":733,"height":125,"caption":"maik"},"logo":{"@id":"https:\/\/truckonline.de\/blog\/wp-content\/uploads\/2019\/12\/logoinnenweiss.png"},"sameAs":["https:\/\/www.facebook.com\/truckblog","https:\/\/www.instagram.com\/truck_online\/","https:\/\/x.com\/https:\/\/twitter.com\/truckblog","https:\/\/www.youtube.com\/user\/truckonline","https:\/\/www.tumblr.com\/truckonline"]}]}},"_links":{"self":[{"href":"https:\/\/truckonline.de\/blog\/wp-json\/wp\/v2\/posts\/923","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/truckonline.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/truckonline.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/truckonline.de\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/truckonline.de\/blog\/wp-json\/wp\/v2\/comments?post=923"}],"version-history":[{"count":0,"href":"https:\/\/truckonline.de\/blog\/wp-json\/wp\/v2\/posts\/923\/revisions"}],"wp:attachment":[{"href":"https:\/\/truckonline.de\/blog\/wp-json\/wp\/v2\/media?parent=923"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/truckonline.de\/blog\/wp-json\/wp\/v2\/categories?post=923"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/truckonline.de\/blog\/wp-json\/wp\/v2\/tags?post=923"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}