{"id":3026,"date":"2012-10-02T00:02:32","date_gmt":"2012-10-01T22:02:32","guid":{"rendered":"https:\/\/truckonline.de\/blog\/?p=3026"},"modified":"2012-10-02T00:37:50","modified_gmt":"2012-10-01T22:37:50","slug":"asphalt-cowboys","status":"publish","type":"post","link":"https:\/\/truckonline.de\/blog\/2012\/10\/02\/asphalt-cowboys\/","title":{"rendered":"Asphalt &#8211; Cowboys"},"content":{"rendered":"<p>Vor etwa einem Jahr fragte eine Produktionsgesellschaft bei mir nach, ob ich Interesse h\u00e4tte, bei einer &#8222;<em>Dokusoap<\/em>&#8220; mitzuwirken. F\u00fcr diese Serie sollten mehrere Lkw-Fahrer einige Wochen lang auf Ihren Touren begleitet werden.<br \/>\nUnter Vorbehalt sagte ich zu. Nach einigen Terminschwierigkeiten klappte es schlie\u00dflich mit einem Treffen auf dem Rasthof &#8222;Irschenberg&#8220;, an der A 8 zwischen M\u00fcnchen und Salzburg.<\/p>\n<p>Dort erfuhr ich, dass der Sender &#8222;<a href=\"https:\/\/www.dmax.de\" target=\"_blank\">DMAX<\/a>&#8220; eine eigene Serie plant. Damals stand weder der Titel, noch das genaue Format fest. Geplant war bis dahin nur, dass der Autohof Berg in Oberfranken Dreh- und Angelpunkt der Serie werden soll.<\/p>\n<p>Damit war das Thema f\u00fcr mich schon erledigt. Die A 9 zwischen N\u00fcrnberg und Leipzig ist halt nicht mein <em>Revier<\/em>. Es wurden noch einige Probeaufnahmen gemacht und anschlie\u00dfend verabschiedeten wir uns freundlich.<br \/>\nSeitdem h\u00f6rte ich nichts mehr von denen.<\/p>\n<p>Vorhin sah ich ein Werbeplakat, auf dem f\u00fcr eine <a href=\"https:\/\/www.dmax.de\/web\/asphalt-cowboys\/serie\/\" target=\"_blank\">neue Serie<\/a> mit dem Titel &#8222;Asphalt-Cowboys&#8220; geworben wird. Auf der dazugeh\u00f6rigen <a href=\"https:\/\/www.dmax.de\/web\/asphalt-cowboys\/\" target=\"_blank\">Infoseite<\/a> erf\u00e4hrt man:<\/p>\n<blockquote><p>DMAX geht mit den K\u00f6nigen der Autobahn auf gro\u00dfe Fahrt quer durch Europa, von Rostock bis Mailand. Sprecher der neuen Doku-Serie ist S\u00e4nger und Trucker-Idol Gunter Gabriel &#8211; der deutsche &#8222;Johnny Cash&#8220;.<\/p><\/blockquote>\n<p>Irgendwo habe ich gelesen, dass es die wohl bisher aufwendigste DMAX-Eigenproduktion ist und f\u00fcr&#8217;s erste vier Folgen geplant sind. Ich werde wohl auf die Wiederholung warten m\u00fcssen &#8211; denn Dienstag ist f\u00fcr mich TV-freie Zeit.<\/p>\n<p><a href=\"https:\/\/truckonline.de\/blog\/wp-content\/uploads\/2012\/10\/lebenaufderstrasse.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/truckonline.de\/blog\/wp-content\/uploads\/2012\/10\/lebenaufderstrasse-309x412.jpg\" alt=\"Leben auf der Strasse\" title=\"lebenaufderstrasse\" width=\"309\" height=\"412\" class=\"alignnone size-medium wp-image-3027\" srcset=\"https:\/\/truckonline.de\/blog\/wp-content\/uploads\/2012\/10\/lebenaufderstrasse-309x412.jpg 309w, https:\/\/truckonline.de\/blog\/wp-content\/uploads\/2012\/10\/lebenaufderstrasse.jpg 550w\" sizes=\"auto, (max-width: 309px) 100vw, 309px\" \/><\/a> <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vor etwa einem Jahr fragte eine Produktionsgesellschaft bei mir nach, ob ich Interesse h\u00e4tte, bei einer &#8222;Dokusoap&#8220; mitzuwirken. F\u00fcr diese Serie sollten mehrere Lkw-Fahrer einige&#8230;<\/p>\n<div class=\"more-link-wrapper\"><a class=\"more-link\" href=\"https:\/\/truckonline.de\/blog\/2012\/10\/02\/asphalt-cowboys\/\">Sie haben Ihr Ziel fast erreicht.<span class=\"screen-reader-text\">Asphalt &#8211; Cowboys<\/span><\/a><\/div>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"iawp_total_views":1,"_metis_text_type":"","_metis_text_length":0,"_post_count":0,"footnotes":""},"categories":[3,191],"tags":[1620,549],"class_list":["post-3026","post","type-post","status-publish","format-standard","hentry","category-internes","category-presse","tag-serie","tag-tv","ratio-2-1","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Asphalt - Cowboys | TruckOnline.de<\/title>\n<meta name=\"description\" content=\"Vor etwa einem Jahr fragte eine Produktionsgesellschaft bei mir nach, ob ich Interesse h\u00e4tte, bei einer &quot;Dokusoap&quot; mitzuwirken. F\u00fcr diese Serie sollten\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/truckonline.de\/blog\/2012\/10\/02\/asphalt-cowboys\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Asphalt - Cowboys | TruckOnline.de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/truckonline.de\/blog\/2012\/10\/02\/asphalt-cowboys\/\" \/>\n<meta property=\"og:site_name\" content=\"TruckOnline.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/truckblog\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/truckblog\" \/>\n<meta property=\"article:published_time\" content=\"2012-10-01T22:02:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2012-10-01T22:37:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/truckonline.de\/blog\/wp-content\/uploads\/2012\/10\/lebenaufderstrasse-309x412.jpg\" \/>\n<meta name=\"author\" content=\"maik\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/truckblog\" \/>\n<meta name=\"twitter:site\" content=\"@truckblog\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"maik\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/2012\\\/10\\\/02\\\/asphalt-cowboys\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/2012\\\/10\\\/02\\\/asphalt-cowboys\\\/\"},\"author\":{\"name\":\"maik\",\"@id\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/#\\\/schema\\\/person\\\/4cb59b86ffde81f882f56439688fda19\"},\"headline\":\"Asphalt &#8211; Cowboys\",\"datePublished\":\"2012-10-01T22:02:32+00:00\",\"dateModified\":\"2012-10-01T22:37:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/2012\\\/10\\\/02\\\/asphalt-cowboys\\\/\"},\"wordCount\":245,\"commentCount\":7,\"publisher\":{\"@id\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/#\\\/schema\\\/person\\\/4cb59b86ffde81f882f56439688fda19\"},\"image\":{\"@id\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/2012\\\/10\\\/02\\\/asphalt-cowboys\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/wp-content\\\/uploads\\\/2012\\\/10\\\/lebenaufderstrasse-309x412.jpg\",\"keywords\":[\"Serie\",\"TV\"],\"articleSection\":[\"Internes\",\"Presse\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/truckonline.de\\\/blog\\\/2012\\\/10\\\/02\\\/asphalt-cowboys\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/2012\\\/10\\\/02\\\/asphalt-cowboys\\\/\",\"url\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/2012\\\/10\\\/02\\\/asphalt-cowboys\\\/\",\"name\":\"Asphalt - Cowboys | TruckOnline.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/2012\\\/10\\\/02\\\/asphalt-cowboys\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/2012\\\/10\\\/02\\\/asphalt-cowboys\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/wp-content\\\/uploads\\\/2012\\\/10\\\/lebenaufderstrasse-309x412.jpg\",\"datePublished\":\"2012-10-01T22:02:32+00:00\",\"dateModified\":\"2012-10-01T22:37:50+00:00\",\"description\":\"Vor etwa einem Jahr fragte eine Produktionsgesellschaft bei mir nach, ob ich Interesse h\u00e4tte, bei einer \\\"Dokusoap\\\" mitzuwirken. F\u00fcr diese Serie sollten\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/2012\\\/10\\\/02\\\/asphalt-cowboys\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/truckonline.de\\\/blog\\\/2012\\\/10\\\/02\\\/asphalt-cowboys\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/2012\\\/10\\\/02\\\/asphalt-cowboys\\\/#primaryimage\",\"url\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/wp-content\\\/uploads\\\/2012\\\/10\\\/lebenaufderstrasse.jpg\",\"contentUrl\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/wp-content\\\/uploads\\\/2012\\\/10\\\/lebenaufderstrasse.jpg\",\"width\":\"550\",\"height\":\"733\",\"caption\":\"Leben auf der Strasse\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/2012\\\/10\\\/02\\\/asphalt-cowboys\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Asphalt &#8211; Cowboys\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/\",\"name\":\"TruckOnline.de\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/#\\\/schema\\\/person\\\/4cb59b86ffde81f882f56439688fda19\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/#\\\/schema\\\/person\\\/4cb59b86ffde81f882f56439688fda19\",\"name\":\"maik\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/logoinnenweiss.png\",\"url\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/logoinnenweiss.png\",\"contentUrl\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/logoinnenweiss.png\",\"width\":733,\"height\":125,\"caption\":\"maik\"},\"logo\":{\"@id\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/logoinnenweiss.png\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/truckblog\",\"https:\\\/\\\/www.instagram.com\\\/truck_online\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/truckblog\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/truckonline\",\"https:\\\/\\\/www.tumblr.com\\\/truckonline\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Asphalt - Cowboys | TruckOnline.de","description":"Vor etwa einem Jahr fragte eine Produktionsgesellschaft bei mir nach, ob ich Interesse h\u00e4tte, bei einer \"Dokusoap\" mitzuwirken. F\u00fcr diese Serie sollten","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/truckonline.de\/blog\/2012\/10\/02\/asphalt-cowboys\/","og_locale":"de_DE","og_type":"article","og_title":"Asphalt - Cowboys | TruckOnline.de","og_url":"https:\/\/truckonline.de\/blog\/2012\/10\/02\/asphalt-cowboys\/","og_site_name":"TruckOnline.de","article_publisher":"https:\/\/www.facebook.com\/truckblog","article_author":"https:\/\/www.facebook.com\/truckblog","article_published_time":"2012-10-01T22:02:32+00:00","article_modified_time":"2012-10-01T22:37:50+00:00","og_image":[{"url":"https:\/\/truckonline.de\/blog\/wp-content\/uploads\/2012\/10\/lebenaufderstrasse-309x412.jpg","type":"","width":"","height":""}],"author":"maik","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/truckblog","twitter_site":"@truckblog","twitter_misc":{"Verfasst von":"maik","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/truckonline.de\/blog\/2012\/10\/02\/asphalt-cowboys\/#article","isPartOf":{"@id":"https:\/\/truckonline.de\/blog\/2012\/10\/02\/asphalt-cowboys\/"},"author":{"name":"maik","@id":"https:\/\/truckonline.de\/blog\/#\/schema\/person\/4cb59b86ffde81f882f56439688fda19"},"headline":"Asphalt &#8211; Cowboys","datePublished":"2012-10-01T22:02:32+00:00","dateModified":"2012-10-01T22:37:50+00:00","mainEntityOfPage":{"@id":"https:\/\/truckonline.de\/blog\/2012\/10\/02\/asphalt-cowboys\/"},"wordCount":245,"commentCount":7,"publisher":{"@id":"https:\/\/truckonline.de\/blog\/#\/schema\/person\/4cb59b86ffde81f882f56439688fda19"},"image":{"@id":"https:\/\/truckonline.de\/blog\/2012\/10\/02\/asphalt-cowboys\/#primaryimage"},"thumbnailUrl":"https:\/\/truckonline.de\/blog\/wp-content\/uploads\/2012\/10\/lebenaufderstrasse-309x412.jpg","keywords":["Serie","TV"],"articleSection":["Internes","Presse"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/truckonline.de\/blog\/2012\/10\/02\/asphalt-cowboys\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/truckonline.de\/blog\/2012\/10\/02\/asphalt-cowboys\/","url":"https:\/\/truckonline.de\/blog\/2012\/10\/02\/asphalt-cowboys\/","name":"Asphalt - Cowboys | TruckOnline.de","isPartOf":{"@id":"https:\/\/truckonline.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/truckonline.de\/blog\/2012\/10\/02\/asphalt-cowboys\/#primaryimage"},"image":{"@id":"https:\/\/truckonline.de\/blog\/2012\/10\/02\/asphalt-cowboys\/#primaryimage"},"thumbnailUrl":"https:\/\/truckonline.de\/blog\/wp-content\/uploads\/2012\/10\/lebenaufderstrasse-309x412.jpg","datePublished":"2012-10-01T22:02:32+00:00","dateModified":"2012-10-01T22:37:50+00:00","description":"Vor etwa einem Jahr fragte eine Produktionsgesellschaft bei mir nach, ob ich Interesse h\u00e4tte, bei einer \"Dokusoap\" mitzuwirken. F\u00fcr diese Serie sollten","breadcrumb":{"@id":"https:\/\/truckonline.de\/blog\/2012\/10\/02\/asphalt-cowboys\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/truckonline.de\/blog\/2012\/10\/02\/asphalt-cowboys\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/truckonline.de\/blog\/2012\/10\/02\/asphalt-cowboys\/#primaryimage","url":"https:\/\/truckonline.de\/blog\/wp-content\/uploads\/2012\/10\/lebenaufderstrasse.jpg","contentUrl":"https:\/\/truckonline.de\/blog\/wp-content\/uploads\/2012\/10\/lebenaufderstrasse.jpg","width":"550","height":"733","caption":"Leben auf der Strasse"},{"@type":"BreadcrumbList","@id":"https:\/\/truckonline.de\/blog\/2012\/10\/02\/asphalt-cowboys\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/truckonline.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Asphalt &#8211; Cowboys"}]},{"@type":"WebSite","@id":"https:\/\/truckonline.de\/blog\/#website","url":"https:\/\/truckonline.de\/blog\/","name":"TruckOnline.de","description":"","publisher":{"@id":"https:\/\/truckonline.de\/blog\/#\/schema\/person\/4cb59b86ffde81f882f56439688fda19"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/truckonline.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/truckonline.de\/blog\/#\/schema\/person\/4cb59b86ffde81f882f56439688fda19","name":"maik","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/truckonline.de\/blog\/wp-content\/uploads\/2019\/12\/logoinnenweiss.png","url":"https:\/\/truckonline.de\/blog\/wp-content\/uploads\/2019\/12\/logoinnenweiss.png","contentUrl":"https:\/\/truckonline.de\/blog\/wp-content\/uploads\/2019\/12\/logoinnenweiss.png","width":733,"height":125,"caption":"maik"},"logo":{"@id":"https:\/\/truckonline.de\/blog\/wp-content\/uploads\/2019\/12\/logoinnenweiss.png"},"sameAs":["https:\/\/www.facebook.com\/truckblog","https:\/\/www.instagram.com\/truck_online\/","https:\/\/x.com\/https:\/\/twitter.com\/truckblog","https:\/\/www.youtube.com\/user\/truckonline","https:\/\/www.tumblr.com\/truckonline"]}]}},"_links":{"self":[{"href":"https:\/\/truckonline.de\/blog\/wp-json\/wp\/v2\/posts\/3026","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/truckonline.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/truckonline.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/truckonline.de\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/truckonline.de\/blog\/wp-json\/wp\/v2\/comments?post=3026"}],"version-history":[{"count":4,"href":"https:\/\/truckonline.de\/blog\/wp-json\/wp\/v2\/posts\/3026\/revisions"}],"predecessor-version":[{"id":3031,"href":"https:\/\/truckonline.de\/blog\/wp-json\/wp\/v2\/posts\/3026\/revisions\/3031"}],"wp:attachment":[{"href":"https:\/\/truckonline.de\/blog\/wp-json\/wp\/v2\/media?parent=3026"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/truckonline.de\/blog\/wp-json\/wp\/v2\/categories?post=3026"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/truckonline.de\/blog\/wp-json\/wp\/v2\/tags?post=3026"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}