{"id":272,"date":"2008-04-05T00:45:01","date_gmt":"2008-04-04T23:45:01","guid":{"rendered":"https:\/\/truckonline.wordpress.com\/?p=147"},"modified":"2008-04-05T00:45:01","modified_gmt":"2008-04-04T23:45:01","slug":"wir-sind-kein-volk","status":"publish","type":"post","link":"https:\/\/truckonline.de\/blog\/2008\/04\/05\/wir-sind-kein-volk\/","title":{"rendered":"Wir sind (k)ein Volk"},"content":{"rendered":"<p>Kommt man an einem Freitag um 13.00 Uhr zu seiner letzten Ladestelle, hat man noch gute Laune. Wenn einem dann ein griesgr\u00e4miger Lagerist entgegnet: &#8222;Vor 16.00 Uhr ist Dein Zeug nicht fertig&#8220;, sinkt diese schon rapide.<\/p>\n<p>Steht man um 17.00 Uhr noch immer ohne das was passiert, ist die Laune fast auf dem Nullpunkt. Endg\u00fcltig in den Minusbereich sinkt diese dann, wenn man endlich an die Rampe &#8222;andocken&#8220; darf, dabei eine schmale Dorfstrasse benutzen muss (die durch eine Baustelle noch enger wurde) und dabei von einer motorisierten Dorfbewohnerin dumm angemacht wird.<\/p>\n<p>Diese &#8222;gute Frau&#8220; war doch tats\u00e4chlich der Meinung, ich w\u00fcrde Sie n\u00f6tigen, da Sie wegen mir kurz halten musste.<br \/>\nSie stieg aus, kam zum Lkw gewackelt und redete auf mich ein. Nach drei oder vier S\u00e4tzen unterbrach ich Sie und fragte, ob Sie nur auf diese Art M\u00e4nner kennen lernt.<\/p>\n<p>Nun verstummte Sie, st\u00f6ckelte zu Ihrem Auto zur\u00fcck und redete auf einen \u00e4lteren Bauarbeiter mit &#8222;etwas&#8220; ger\u00f6teten Gesicht ein.<br \/>\nDieser beteiligte sich nun auch an unseren Disput, dabei ergriff er (logischerweise) Partei f\u00fcr die Frau.<\/p>\n<p>Nun sah ich mich gen\u00f6tigt auszusteigen. Ich fragte diesen Strassenbauhilfsarbeiter, ob denn sein Alkohol alle w\u00e4re.<br \/>\nEr entgegnete mir, er w\u00fcrde nicht trinken, sondern h\u00e4tte nur einen Sprachfehler. Nur war mir das bisher \u00fcberhaupt nicht aufgefallen, sondern nur sein rotes Gesicht.<\/p>\n<p>Was dann kam, erstaunte selbst mich:<br \/>\nDorfbewohnerin: &#8222;Diese Ossis d\u00fcrfen sich hier alles erlauben&#8220;!<br \/>\nBauhilfsarbeiter: &#8222;Genau, dieses dreckigen Ossis&#8220;!<br \/>\nDorfbewohnerin: &#8222;Das trage ich dem Kohl noch heute nach, dass er die ins Land geholt hat&#8220;!<br \/>\nBauhilfsarbeiter: wollte irgendwas sagen, bekam aber kein Wort heraus. Ob es am Entzug lag oder er doch einen Sprachfehler hatte? Keine Ahnung!<\/p>\n<p>Immerhin war die &#8222;Unterhaltung&#8220; damit beendet&#8230;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Kommt man an einem Freitag um 13.00 Uhr zu seiner letzten Ladestelle, hat man noch gute Laune. Wenn einem dann ein griesgr\u00e4miger Lagerist entgegnet: &#8222;Vor&#8230;<\/p>\n<div class=\"more-link-wrapper\"><a class=\"more-link\" href=\"https:\/\/truckonline.de\/blog\/2008\/04\/05\/wir-sind-kein-volk\/\">Sie haben Ihr Ziel fast erreicht.<span class=\"screen-reader-text\">Wir sind (k)ein Volk<\/span><\/a><\/div>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"iawp_total_views":1,"_metis_text_type":"","_metis_text_length":0,"_post_count":0,"footnotes":""},"categories":[593,24],"tags":[376,430,581],"class_list":["post-272","post","type-post","status-publish","format-standard","hentry","category-aergerliches","category-unterwegs","tag-laune","tag-ossi","tag-wessi","ratio-2-1","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Wir sind (k)ein Volk | TruckOnline.de<\/title>\n<meta name=\"description\" content=\"Kommt man an einem Freitag um 13.00 Uhr zu seiner letzten Ladestelle, hat man noch gute Laune. Wenn einem dann ein griesgr\u00e4miger Lagerist entgegnet: &quot;Vor\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/truckonline.de\/blog\/2008\/04\/05\/wir-sind-kein-volk\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wir sind (k)ein Volk | TruckOnline.de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/truckonline.de\/blog\/2008\/04\/05\/wir-sind-kein-volk\/\" \/>\n<meta property=\"og:site_name\" content=\"TruckOnline.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/truckblog\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/truckblog\" \/>\n<meta property=\"article:published_time\" content=\"2008-04-04T23:45:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/truckonline.de\/blog\/wp-content\/uploads\/2019\/12\/IMG_20191229_225424-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"maik\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/truckblog\" \/>\n<meta name=\"twitter:site\" content=\"@truckblog\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"maik\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/2008\\\/04\\\/05\\\/wir-sind-kein-volk\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/2008\\\/04\\\/05\\\/wir-sind-kein-volk\\\/\"},\"author\":{\"name\":\"maik\",\"@id\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/#\\\/schema\\\/person\\\/4cb59b86ffde81f882f56439688fda19\"},\"headline\":\"Wir sind (k)ein Volk\",\"datePublished\":\"2008-04-04T23:45:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/2008\\\/04\\\/05\\\/wir-sind-kein-volk\\\/\"},\"wordCount\":298,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/#\\\/schema\\\/person\\\/4cb59b86ffde81f882f56439688fda19\"},\"keywords\":[\"Laune\",\"Ossi\",\"Wessi\"],\"articleSection\":[\"\u00c4rgerliches\",\"Unterwegs\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/truckonline.de\\\/blog\\\/2008\\\/04\\\/05\\\/wir-sind-kein-volk\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/2008\\\/04\\\/05\\\/wir-sind-kein-volk\\\/\",\"url\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/2008\\\/04\\\/05\\\/wir-sind-kein-volk\\\/\",\"name\":\"Wir sind (k)ein Volk | TruckOnline.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/#website\"},\"datePublished\":\"2008-04-04T23:45:01+00:00\",\"description\":\"Kommt man an einem Freitag um 13.00 Uhr zu seiner letzten Ladestelle, hat man noch gute Laune. Wenn einem dann ein griesgr\u00e4miger Lagerist entgegnet: \\\"Vor\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/2008\\\/04\\\/05\\\/wir-sind-kein-volk\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/truckonline.de\\\/blog\\\/2008\\\/04\\\/05\\\/wir-sind-kein-volk\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/2008\\\/04\\\/05\\\/wir-sind-kein-volk\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Wir sind (k)ein Volk\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/\",\"name\":\"TruckOnline.de\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/#\\\/schema\\\/person\\\/4cb59b86ffde81f882f56439688fda19\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/#\\\/schema\\\/person\\\/4cb59b86ffde81f882f56439688fda19\",\"name\":\"maik\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/logoinnenweiss.png\",\"url\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/logoinnenweiss.png\",\"contentUrl\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/logoinnenweiss.png\",\"width\":733,\"height\":125,\"caption\":\"maik\"},\"logo\":{\"@id\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/logoinnenweiss.png\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/truckblog\",\"https:\\\/\\\/www.instagram.com\\\/truck_online\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/truckblog\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/truckonline\",\"https:\\\/\\\/www.tumblr.com\\\/truckonline\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Wir sind (k)ein Volk | TruckOnline.de","description":"Kommt man an einem Freitag um 13.00 Uhr zu seiner letzten Ladestelle, hat man noch gute Laune. Wenn einem dann ein griesgr\u00e4miger Lagerist entgegnet: \"Vor","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/truckonline.de\/blog\/2008\/04\/05\/wir-sind-kein-volk\/","og_locale":"de_DE","og_type":"article","og_title":"Wir sind (k)ein Volk | TruckOnline.de","og_url":"https:\/\/truckonline.de\/blog\/2008\/04\/05\/wir-sind-kein-volk\/","og_site_name":"TruckOnline.de","article_publisher":"https:\/\/www.facebook.com\/truckblog","article_author":"https:\/\/www.facebook.com\/truckblog","article_published_time":"2008-04-04T23:45:01+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/truckonline.de\/blog\/wp-content\/uploads\/2019\/12\/IMG_20191229_225424-scaled.jpg","type":"image\/jpeg"}],"author":"maik","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/truckblog","twitter_site":"@truckblog","twitter_misc":{"Verfasst von":"maik","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/truckonline.de\/blog\/2008\/04\/05\/wir-sind-kein-volk\/#article","isPartOf":{"@id":"https:\/\/truckonline.de\/blog\/2008\/04\/05\/wir-sind-kein-volk\/"},"author":{"name":"maik","@id":"https:\/\/truckonline.de\/blog\/#\/schema\/person\/4cb59b86ffde81f882f56439688fda19"},"headline":"Wir sind (k)ein Volk","datePublished":"2008-04-04T23:45:01+00:00","mainEntityOfPage":{"@id":"https:\/\/truckonline.de\/blog\/2008\/04\/05\/wir-sind-kein-volk\/"},"wordCount":298,"commentCount":0,"publisher":{"@id":"https:\/\/truckonline.de\/blog\/#\/schema\/person\/4cb59b86ffde81f882f56439688fda19"},"keywords":["Laune","Ossi","Wessi"],"articleSection":["\u00c4rgerliches","Unterwegs"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/truckonline.de\/blog\/2008\/04\/05\/wir-sind-kein-volk\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/truckonline.de\/blog\/2008\/04\/05\/wir-sind-kein-volk\/","url":"https:\/\/truckonline.de\/blog\/2008\/04\/05\/wir-sind-kein-volk\/","name":"Wir sind (k)ein Volk | TruckOnline.de","isPartOf":{"@id":"https:\/\/truckonline.de\/blog\/#website"},"datePublished":"2008-04-04T23:45:01+00:00","description":"Kommt man an einem Freitag um 13.00 Uhr zu seiner letzten Ladestelle, hat man noch gute Laune. Wenn einem dann ein griesgr\u00e4miger Lagerist entgegnet: \"Vor","breadcrumb":{"@id":"https:\/\/truckonline.de\/blog\/2008\/04\/05\/wir-sind-kein-volk\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/truckonline.de\/blog\/2008\/04\/05\/wir-sind-kein-volk\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/truckonline.de\/blog\/2008\/04\/05\/wir-sind-kein-volk\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/truckonline.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Wir sind (k)ein Volk"}]},{"@type":"WebSite","@id":"https:\/\/truckonline.de\/blog\/#website","url":"https:\/\/truckonline.de\/blog\/","name":"TruckOnline.de","description":"","publisher":{"@id":"https:\/\/truckonline.de\/blog\/#\/schema\/person\/4cb59b86ffde81f882f56439688fda19"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/truckonline.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/truckonline.de\/blog\/#\/schema\/person\/4cb59b86ffde81f882f56439688fda19","name":"maik","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/truckonline.de\/blog\/wp-content\/uploads\/2019\/12\/logoinnenweiss.png","url":"https:\/\/truckonline.de\/blog\/wp-content\/uploads\/2019\/12\/logoinnenweiss.png","contentUrl":"https:\/\/truckonline.de\/blog\/wp-content\/uploads\/2019\/12\/logoinnenweiss.png","width":733,"height":125,"caption":"maik"},"logo":{"@id":"https:\/\/truckonline.de\/blog\/wp-content\/uploads\/2019\/12\/logoinnenweiss.png"},"sameAs":["https:\/\/www.facebook.com\/truckblog","https:\/\/www.instagram.com\/truck_online\/","https:\/\/x.com\/https:\/\/twitter.com\/truckblog","https:\/\/www.youtube.com\/user\/truckonline","https:\/\/www.tumblr.com\/truckonline"]}]}},"_links":{"self":[{"href":"https:\/\/truckonline.de\/blog\/wp-json\/wp\/v2\/posts\/272","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/truckonline.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/truckonline.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/truckonline.de\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/truckonline.de\/blog\/wp-json\/wp\/v2\/comments?post=272"}],"version-history":[{"count":0,"href":"https:\/\/truckonline.de\/blog\/wp-json\/wp\/v2\/posts\/272\/revisions"}],"wp:attachment":[{"href":"https:\/\/truckonline.de\/blog\/wp-json\/wp\/v2\/media?parent=272"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/truckonline.de\/blog\/wp-json\/wp\/v2\/categories?post=272"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/truckonline.de\/blog\/wp-json\/wp\/v2\/tags?post=272"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}