{"id":1631,"date":"2010-12-27T21:36:55","date_gmt":"2010-12-27T20:36:55","guid":{"rendered":"https:\/\/truckonline.de\/blog\/?p=1631"},"modified":"2010-12-27T21:36:55","modified_gmt":"2010-12-27T20:36:55","slug":"zu-schnell-im-schnee-schadenersatz-dennoch-moeglich","status":"publish","type":"post","link":"https:\/\/truckonline.de\/blog\/2010\/12\/27\/zu-schnell-im-schnee-schadenersatz-dennoch-moeglich\/","title":{"rendered":"Zu schnell im Schnee: Schadenersatz dennoch m\u00f6glich"},"content":{"rendered":"<p>Diese Urteilsbegr\u00fcndung klingt doch gut:<\/p>\n<blockquote><p>Die nicht angepasste Geschwindigkeit ist kein schwerwiegender Versto\u00df, weil dieses Fehlverhalten im Lkw-Verkehr st\u00e4ndig zu beobachten ist.<\/p><\/blockquote>\n<p>Einem Lkw-Fahrer steht nach einem Unfall auch dann Schadenersatz zu, wenn er seine Geschwindigkeit nicht den aktuellen Wetterverh\u00e4ltnissen angepasst hatte. Das hat das Landgericht Eilwangen entschieden (Aktenzeichen: 1 S 107\/10).<\/p>\n<p>Weiter <a href=\"https:\/\/newsticker.sueddeutsche.de\/list\/id\/1088576\">>>><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Diese Urteilsbegr\u00fcndung klingt doch gut: Die nicht angepasste Geschwindigkeit ist kein schwerwiegender Versto\u00df, weil dieses Fehlverhalten im Lkw-Verkehr st\u00e4ndig zu beobachten ist. Einem Lkw-Fahrer steht&#8230;<\/p>\n<div class=\"more-link-wrapper\"><a class=\"more-link\" href=\"https:\/\/truckonline.de\/blog\/2010\/12\/27\/zu-schnell-im-schnee-schadenersatz-dennoch-moeglich\/\">Sie haben Ihr Ziel fast erreicht.<span class=\"screen-reader-text\">Zu schnell im Schnee: Schadenersatz dennoch m\u00f6glich<\/span><\/a><\/div>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"iawp_total_views":1,"_metis_text_type":"","_metis_text_length":0,"_post_count":0,"footnotes":""},"categories":[1,52],"tags":[1890,562],"class_list":["post-1631","post","type-post","status-publish","format-standard","hentry","category-allgemeines","category-unfall","tag-unfall","tag-urteil","ratio-2-1","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Zu schnell im Schnee: Schadenersatz dennoch m\u00f6glich | TruckOnline.de<\/title>\n<meta name=\"description\" content=\"Diese Urteilsbegr\u00fcndung klingt doch gut: Die nicht angepasste Geschwindigkeit ist kein schwerwiegender Versto\u00df, weil dieses Fehlverhalten im Lkw-Verkehr\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/truckonline.de\/blog\/2010\/12\/27\/zu-schnell-im-schnee-schadenersatz-dennoch-moeglich\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Zu schnell im Schnee: Schadenersatz dennoch m\u00f6glich | TruckOnline.de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/truckonline.de\/blog\/2010\/12\/27\/zu-schnell-im-schnee-schadenersatz-dennoch-moeglich\/\" \/>\n<meta property=\"og:site_name\" content=\"TruckOnline.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/truckblog\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/truckblog\" \/>\n<meta property=\"article:published_time\" content=\"2010-12-27T20:36:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/truckonline.de\/blog\/wp-content\/uploads\/2019\/12\/IMG_20191229_225424-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"maik\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/truckblog\" \/>\n<meta name=\"twitter:site\" content=\"@truckblog\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"maik\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/2010\\\/12\\\/27\\\/zu-schnell-im-schnee-schadenersatz-dennoch-moeglich\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/2010\\\/12\\\/27\\\/zu-schnell-im-schnee-schadenersatz-dennoch-moeglich\\\/\"},\"author\":{\"name\":\"maik\",\"@id\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/#\\\/schema\\\/person\\\/4cb59b86ffde81f882f56439688fda19\"},\"headline\":\"Zu schnell im Schnee: Schadenersatz dennoch m\u00f6glich\",\"datePublished\":\"2010-12-27T20:36:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/2010\\\/12\\\/27\\\/zu-schnell-im-schnee-schadenersatz-dennoch-moeglich\\\/\"},\"wordCount\":62,\"commentCount\":3,\"publisher\":{\"@id\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/#\\\/schema\\\/person\\\/4cb59b86ffde81f882f56439688fda19\"},\"keywords\":[\"Unfall\",\"Urteil\"],\"articleSection\":[\"Allgemeines\",\"Unfall\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/truckonline.de\\\/blog\\\/2010\\\/12\\\/27\\\/zu-schnell-im-schnee-schadenersatz-dennoch-moeglich\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/2010\\\/12\\\/27\\\/zu-schnell-im-schnee-schadenersatz-dennoch-moeglich\\\/\",\"url\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/2010\\\/12\\\/27\\\/zu-schnell-im-schnee-schadenersatz-dennoch-moeglich\\\/\",\"name\":\"Zu schnell im Schnee: Schadenersatz dennoch m\u00f6glich | TruckOnline.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/#website\"},\"datePublished\":\"2010-12-27T20:36:55+00:00\",\"description\":\"Diese Urteilsbegr\u00fcndung klingt doch gut: Die nicht angepasste Geschwindigkeit ist kein schwerwiegender Versto\u00df, weil dieses Fehlverhalten im Lkw-Verkehr\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/2010\\\/12\\\/27\\\/zu-schnell-im-schnee-schadenersatz-dennoch-moeglich\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/truckonline.de\\\/blog\\\/2010\\\/12\\\/27\\\/zu-schnell-im-schnee-schadenersatz-dennoch-moeglich\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/2010\\\/12\\\/27\\\/zu-schnell-im-schnee-schadenersatz-dennoch-moeglich\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Zu schnell im Schnee: Schadenersatz dennoch m\u00f6glich\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/\",\"name\":\"TruckOnline.de\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/#\\\/schema\\\/person\\\/4cb59b86ffde81f882f56439688fda19\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/#\\\/schema\\\/person\\\/4cb59b86ffde81f882f56439688fda19\",\"name\":\"maik\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/logoinnenweiss.png\",\"url\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/logoinnenweiss.png\",\"contentUrl\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/logoinnenweiss.png\",\"width\":733,\"height\":125,\"caption\":\"maik\"},\"logo\":{\"@id\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/logoinnenweiss.png\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/truckblog\",\"https:\\\/\\\/www.instagram.com\\\/truck_online\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/truckblog\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/truckonline\",\"https:\\\/\\\/www.tumblr.com\\\/truckonline\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Zu schnell im Schnee: Schadenersatz dennoch m\u00f6glich | TruckOnline.de","description":"Diese Urteilsbegr\u00fcndung klingt doch gut: Die nicht angepasste Geschwindigkeit ist kein schwerwiegender Versto\u00df, weil dieses Fehlverhalten im Lkw-Verkehr","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/truckonline.de\/blog\/2010\/12\/27\/zu-schnell-im-schnee-schadenersatz-dennoch-moeglich\/","og_locale":"de_DE","og_type":"article","og_title":"Zu schnell im Schnee: Schadenersatz dennoch m\u00f6glich | TruckOnline.de","og_url":"https:\/\/truckonline.de\/blog\/2010\/12\/27\/zu-schnell-im-schnee-schadenersatz-dennoch-moeglich\/","og_site_name":"TruckOnline.de","article_publisher":"https:\/\/www.facebook.com\/truckblog","article_author":"https:\/\/www.facebook.com\/truckblog","article_published_time":"2010-12-27T20:36:55+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/truckonline.de\/blog\/wp-content\/uploads\/2019\/12\/IMG_20191229_225424-scaled.jpg","type":"image\/jpeg"}],"author":"maik","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/truckblog","twitter_site":"@truckblog","twitter_misc":{"Verfasst von":"maik"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/truckonline.de\/blog\/2010\/12\/27\/zu-schnell-im-schnee-schadenersatz-dennoch-moeglich\/#article","isPartOf":{"@id":"https:\/\/truckonline.de\/blog\/2010\/12\/27\/zu-schnell-im-schnee-schadenersatz-dennoch-moeglich\/"},"author":{"name":"maik","@id":"https:\/\/truckonline.de\/blog\/#\/schema\/person\/4cb59b86ffde81f882f56439688fda19"},"headline":"Zu schnell im Schnee: Schadenersatz dennoch m\u00f6glich","datePublished":"2010-12-27T20:36:55+00:00","mainEntityOfPage":{"@id":"https:\/\/truckonline.de\/blog\/2010\/12\/27\/zu-schnell-im-schnee-schadenersatz-dennoch-moeglich\/"},"wordCount":62,"commentCount":3,"publisher":{"@id":"https:\/\/truckonline.de\/blog\/#\/schema\/person\/4cb59b86ffde81f882f56439688fda19"},"keywords":["Unfall","Urteil"],"articleSection":["Allgemeines","Unfall"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/truckonline.de\/blog\/2010\/12\/27\/zu-schnell-im-schnee-schadenersatz-dennoch-moeglich\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/truckonline.de\/blog\/2010\/12\/27\/zu-schnell-im-schnee-schadenersatz-dennoch-moeglich\/","url":"https:\/\/truckonline.de\/blog\/2010\/12\/27\/zu-schnell-im-schnee-schadenersatz-dennoch-moeglich\/","name":"Zu schnell im Schnee: Schadenersatz dennoch m\u00f6glich | TruckOnline.de","isPartOf":{"@id":"https:\/\/truckonline.de\/blog\/#website"},"datePublished":"2010-12-27T20:36:55+00:00","description":"Diese Urteilsbegr\u00fcndung klingt doch gut: Die nicht angepasste Geschwindigkeit ist kein schwerwiegender Versto\u00df, weil dieses Fehlverhalten im Lkw-Verkehr","breadcrumb":{"@id":"https:\/\/truckonline.de\/blog\/2010\/12\/27\/zu-schnell-im-schnee-schadenersatz-dennoch-moeglich\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/truckonline.de\/blog\/2010\/12\/27\/zu-schnell-im-schnee-schadenersatz-dennoch-moeglich\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/truckonline.de\/blog\/2010\/12\/27\/zu-schnell-im-schnee-schadenersatz-dennoch-moeglich\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/truckonline.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Zu schnell im Schnee: Schadenersatz dennoch m\u00f6glich"}]},{"@type":"WebSite","@id":"https:\/\/truckonline.de\/blog\/#website","url":"https:\/\/truckonline.de\/blog\/","name":"TruckOnline.de","description":"","publisher":{"@id":"https:\/\/truckonline.de\/blog\/#\/schema\/person\/4cb59b86ffde81f882f56439688fda19"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/truckonline.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/truckonline.de\/blog\/#\/schema\/person\/4cb59b86ffde81f882f56439688fda19","name":"maik","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/truckonline.de\/blog\/wp-content\/uploads\/2019\/12\/logoinnenweiss.png","url":"https:\/\/truckonline.de\/blog\/wp-content\/uploads\/2019\/12\/logoinnenweiss.png","contentUrl":"https:\/\/truckonline.de\/blog\/wp-content\/uploads\/2019\/12\/logoinnenweiss.png","width":733,"height":125,"caption":"maik"},"logo":{"@id":"https:\/\/truckonline.de\/blog\/wp-content\/uploads\/2019\/12\/logoinnenweiss.png"},"sameAs":["https:\/\/www.facebook.com\/truckblog","https:\/\/www.instagram.com\/truck_online\/","https:\/\/x.com\/https:\/\/twitter.com\/truckblog","https:\/\/www.youtube.com\/user\/truckonline","https:\/\/www.tumblr.com\/truckonline"]}]}},"_links":{"self":[{"href":"https:\/\/truckonline.de\/blog\/wp-json\/wp\/v2\/posts\/1631","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/truckonline.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/truckonline.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/truckonline.de\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/truckonline.de\/blog\/wp-json\/wp\/v2\/comments?post=1631"}],"version-history":[{"count":0,"href":"https:\/\/truckonline.de\/blog\/wp-json\/wp\/v2\/posts\/1631\/revisions"}],"wp:attachment":[{"href":"https:\/\/truckonline.de\/blog\/wp-json\/wp\/v2\/media?parent=1631"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/truckonline.de\/blog\/wp-json\/wp\/v2\/categories?post=1631"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/truckonline.de\/blog\/wp-json\/wp\/v2\/tags?post=1631"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}