{"id":1256,"date":"2010-03-19T08:49:23","date_gmt":"2010-03-19T07:49:23","guid":{"rendered":"https:\/\/truckonline.de\/blog\/?p=1256"},"modified":"2010-03-19T08:49:23","modified_gmt":"2010-03-19T07:49:23","slug":"ungewohnt","status":"publish","type":"post","link":"https:\/\/truckonline.de\/blog\/2010\/03\/19\/ungewohnt\/","title":{"rendered":"Ungewohnt"},"content":{"rendered":"<p>Freitagvormittag, dreiviertel neun &#8211; noch knapp zweihundertachtzig Kilometer bis nach Hause. Irgendwie ungewohnt, weil irgendwie verfr\u00fcht. Aber irgendwie sch\u00f6n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Freitagvormittag, dreiviertel neun &#8211; noch knapp zweihundertachtzig Kilometer bis nach Hause. Irgendwie ungewohnt, weil irgendwie verfr\u00fcht. Aber irgendwie sch\u00f6n.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"iawp_total_views":1,"_metis_text_type":"","_metis_text_length":0,"_post_count":0,"footnotes":""},"categories":[3],"tags":[94],"class_list":["post-1256","post","type-post","status-publish","format-standard","hentry","category-internes","tag-wochenende","ratio-2-1","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ungewohnt | TruckOnline.de<\/title>\n<meta name=\"description\" content=\"Freitagvormittag, dreiviertel neun - noch knapp zweihundertachtzig Kilometer bis nach Hause. Irgendwie ungewohnt, weil irgendwie verfr\u00fcht. Aber irgendwie\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/truckonline.de\/blog\/2010\/03\/19\/ungewohnt\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ungewohnt | TruckOnline.de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/truckonline.de\/blog\/2010\/03\/19\/ungewohnt\/\" \/>\n<meta property=\"og:site_name\" content=\"TruckOnline.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/truckblog\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/truckblog\" \/>\n<meta property=\"article:published_time\" content=\"2010-03-19T07:49:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/truckonline.de\/blog\/wp-content\/uploads\/2019\/12\/IMG_20191229_225424-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"maik\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/truckblog\" \/>\n<meta name=\"twitter:site\" content=\"@truckblog\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"maik\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/2010\\\/03\\\/19\\\/ungewohnt\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/2010\\\/03\\\/19\\\/ungewohnt\\\/\"},\"author\":{\"name\":\"maik\",\"@id\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/#\\\/schema\\\/person\\\/4cb59b86ffde81f882f56439688fda19\"},\"headline\":\"Ungewohnt\",\"datePublished\":\"2010-03-19T07:49:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/2010\\\/03\\\/19\\\/ungewohnt\\\/\"},\"wordCount\":22,\"commentCount\":2,\"publisher\":{\"@id\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/#\\\/schema\\\/person\\\/4cb59b86ffde81f882f56439688fda19\"},\"keywords\":[\"Wochenende\"],\"articleSection\":[\"Internes\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/truckonline.de\\\/blog\\\/2010\\\/03\\\/19\\\/ungewohnt\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/2010\\\/03\\\/19\\\/ungewohnt\\\/\",\"url\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/2010\\\/03\\\/19\\\/ungewohnt\\\/\",\"name\":\"Ungewohnt | TruckOnline.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/#website\"},\"datePublished\":\"2010-03-19T07:49:23+00:00\",\"description\":\"Freitagvormittag, dreiviertel neun - noch knapp zweihundertachtzig Kilometer bis nach Hause. Irgendwie ungewohnt, weil irgendwie verfr\u00fcht. Aber irgendwie\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/2010\\\/03\\\/19\\\/ungewohnt\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/truckonline.de\\\/blog\\\/2010\\\/03\\\/19\\\/ungewohnt\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/2010\\\/03\\\/19\\\/ungewohnt\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ungewohnt\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/\",\"name\":\"TruckOnline.de\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/#\\\/schema\\\/person\\\/4cb59b86ffde81f882f56439688fda19\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/#\\\/schema\\\/person\\\/4cb59b86ffde81f882f56439688fda19\",\"name\":\"maik\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/logoinnenweiss.png\",\"url\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/logoinnenweiss.png\",\"contentUrl\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/logoinnenweiss.png\",\"width\":733,\"height\":125,\"caption\":\"maik\"},\"logo\":{\"@id\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/logoinnenweiss.png\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/truckblog\",\"https:\\\/\\\/www.instagram.com\\\/truck_online\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/truckblog\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/truckonline\",\"https:\\\/\\\/www.tumblr.com\\\/truckonline\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ungewohnt | TruckOnline.de","description":"Freitagvormittag, dreiviertel neun - noch knapp zweihundertachtzig Kilometer bis nach Hause. Irgendwie ungewohnt, weil irgendwie verfr\u00fcht. Aber irgendwie","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/truckonline.de\/blog\/2010\/03\/19\/ungewohnt\/","og_locale":"de_DE","og_type":"article","og_title":"Ungewohnt | TruckOnline.de","og_url":"https:\/\/truckonline.de\/blog\/2010\/03\/19\/ungewohnt\/","og_site_name":"TruckOnline.de","article_publisher":"https:\/\/www.facebook.com\/truckblog","article_author":"https:\/\/www.facebook.com\/truckblog","article_published_time":"2010-03-19T07:49:23+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/truckonline.de\/blog\/wp-content\/uploads\/2019\/12\/IMG_20191229_225424-scaled.jpg","type":"image\/jpeg"}],"author":"maik","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/truckblog","twitter_site":"@truckblog","twitter_misc":{"Verfasst von":"maik"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/truckonline.de\/blog\/2010\/03\/19\/ungewohnt\/#article","isPartOf":{"@id":"https:\/\/truckonline.de\/blog\/2010\/03\/19\/ungewohnt\/"},"author":{"name":"maik","@id":"https:\/\/truckonline.de\/blog\/#\/schema\/person\/4cb59b86ffde81f882f56439688fda19"},"headline":"Ungewohnt","datePublished":"2010-03-19T07:49:23+00:00","mainEntityOfPage":{"@id":"https:\/\/truckonline.de\/blog\/2010\/03\/19\/ungewohnt\/"},"wordCount":22,"commentCount":2,"publisher":{"@id":"https:\/\/truckonline.de\/blog\/#\/schema\/person\/4cb59b86ffde81f882f56439688fda19"},"keywords":["Wochenende"],"articleSection":["Internes"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/truckonline.de\/blog\/2010\/03\/19\/ungewohnt\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/truckonline.de\/blog\/2010\/03\/19\/ungewohnt\/","url":"https:\/\/truckonline.de\/blog\/2010\/03\/19\/ungewohnt\/","name":"Ungewohnt | TruckOnline.de","isPartOf":{"@id":"https:\/\/truckonline.de\/blog\/#website"},"datePublished":"2010-03-19T07:49:23+00:00","description":"Freitagvormittag, dreiviertel neun - noch knapp zweihundertachtzig Kilometer bis nach Hause. Irgendwie ungewohnt, weil irgendwie verfr\u00fcht. Aber irgendwie","breadcrumb":{"@id":"https:\/\/truckonline.de\/blog\/2010\/03\/19\/ungewohnt\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/truckonline.de\/blog\/2010\/03\/19\/ungewohnt\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/truckonline.de\/blog\/2010\/03\/19\/ungewohnt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/truckonline.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Ungewohnt"}]},{"@type":"WebSite","@id":"https:\/\/truckonline.de\/blog\/#website","url":"https:\/\/truckonline.de\/blog\/","name":"TruckOnline.de","description":"","publisher":{"@id":"https:\/\/truckonline.de\/blog\/#\/schema\/person\/4cb59b86ffde81f882f56439688fda19"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/truckonline.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/truckonline.de\/blog\/#\/schema\/person\/4cb59b86ffde81f882f56439688fda19","name":"maik","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/truckonline.de\/blog\/wp-content\/uploads\/2019\/12\/logoinnenweiss.png","url":"https:\/\/truckonline.de\/blog\/wp-content\/uploads\/2019\/12\/logoinnenweiss.png","contentUrl":"https:\/\/truckonline.de\/blog\/wp-content\/uploads\/2019\/12\/logoinnenweiss.png","width":733,"height":125,"caption":"maik"},"logo":{"@id":"https:\/\/truckonline.de\/blog\/wp-content\/uploads\/2019\/12\/logoinnenweiss.png"},"sameAs":["https:\/\/www.facebook.com\/truckblog","https:\/\/www.instagram.com\/truck_online\/","https:\/\/x.com\/https:\/\/twitter.com\/truckblog","https:\/\/www.youtube.com\/user\/truckonline","https:\/\/www.tumblr.com\/truckonline"]}]}},"_links":{"self":[{"href":"https:\/\/truckonline.de\/blog\/wp-json\/wp\/v2\/posts\/1256","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/truckonline.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/truckonline.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/truckonline.de\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/truckonline.de\/blog\/wp-json\/wp\/v2\/comments?post=1256"}],"version-history":[{"count":0,"href":"https:\/\/truckonline.de\/blog\/wp-json\/wp\/v2\/posts\/1256\/revisions"}],"wp:attachment":[{"href":"https:\/\/truckonline.de\/blog\/wp-json\/wp\/v2\/media?parent=1256"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/truckonline.de\/blog\/wp-json\/wp\/v2\/categories?post=1256"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/truckonline.de\/blog\/wp-json\/wp\/v2\/tags?post=1256"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}