{"id":1186,"date":"2010-02-06T09:21:52","date_gmt":"2010-02-06T08:21:52","guid":{"rendered":"https:\/\/truckonline.de\/blog\/?p=1186"},"modified":"2010-02-05T20:24:38","modified_gmt":"2010-02-05T19:24:38","slug":"polizei-kosten-bei-panne-muessen-bezahlt-werden","status":"publish","type":"post","link":"https:\/\/truckonline.de\/blog\/2010\/02\/06\/polizei-kosten-bei-panne-muessen-bezahlt-werden\/","title":{"rendered":"Polizei-Kosten bei Panne m\u00fcssen bezahlt werden"},"content":{"rendered":"<p>Wenn die Polizei eine gef\u00e4hrliche Pannenstelle absichert, muss der Eigent\u00fcmer des liegengebliebenen Fahrzeugs die Personalkosten der Beamten \u00fcbernehmen. Das hat das Verwaltungsgericht Trier nach Mitteilung vom Freitag entschieden (Az: 1 K 621\/09.TR). <\/p>\n<p>Damit wurde die Klage einer Firma aus dem Saarland abgewiesen. Diese hatte nicht f\u00fcr die Kosten von 256 Euro aufkommen wollte, die ihr das Land Rheinland-Pfalz nach einer Panne ihres Firmenlasters in Rechnung gestellt hatte. Der defekte Lastwagen war im Juli 2009 auf er B51 bei Trier in einer scharfen Kurve liegengeblieben.<br \/>\nDa auf einspuriger Strecke ein gefahrloses Umfahren nicht m\u00f6glich war, sperrte die Polizei mit vier Beamten die Stra\u00dfe f\u00fcr etwa 90 Minuten.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wenn die Polizei eine gef\u00e4hrliche Pannenstelle absichert, muss der Eigent\u00fcmer des liegengebliebenen Fahrzeugs die Personalkosten der Beamten \u00fcbernehmen. Das hat das Verwaltungsgericht Trier nach Mitteilung&#8230;<\/p>\n<div class=\"more-link-wrapper\"><a class=\"more-link\" href=\"https:\/\/truckonline.de\/blog\/2010\/02\/06\/polizei-kosten-bei-panne-muessen-bezahlt-werden\/\">Sie haben Ihr Ziel fast erreicht.<span class=\"screen-reader-text\">Polizei-Kosten bei Panne m\u00fcssen bezahlt werden<\/span><\/a><\/div>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"iawp_total_views":1,"_metis_text_type":"","_metis_text_length":0,"_post_count":0,"footnotes":""},"categories":[1,11],"tags":[1881,431,190],"class_list":["post-1186","post","type-post","status-publish","format-standard","hentry","category-allgemeines","category-lkw","tag-lkw","tag-panne","tag-polizei","ratio-2-1","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Polizei-Kosten bei Panne m\u00fcssen bezahlt werden | TruckOnline.de<\/title>\n<meta name=\"description\" content=\"Wenn die Polizei eine gef\u00e4hrliche Pannenstelle absichert, muss der Eigent\u00fcmer des liegengebliebenen Fahrzeugs die Personalkosten der Beamten \u00fcbernehmen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/truckonline.de\/blog\/2010\/02\/06\/polizei-kosten-bei-panne-muessen-bezahlt-werden\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Polizei-Kosten bei Panne m\u00fcssen bezahlt werden | TruckOnline.de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/truckonline.de\/blog\/2010\/02\/06\/polizei-kosten-bei-panne-muessen-bezahlt-werden\/\" \/>\n<meta property=\"og:site_name\" content=\"TruckOnline.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/truckblog\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/truckblog\" \/>\n<meta property=\"article:published_time\" content=\"2010-02-06T08:21:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/truckonline.de\/blog\/wp-content\/uploads\/2019\/12\/IMG_20191229_225424-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"maik\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/truckblog\" \/>\n<meta name=\"twitter:site\" content=\"@truckblog\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"maik\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/2010\\\/02\\\/06\\\/polizei-kosten-bei-panne-muessen-bezahlt-werden\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/2010\\\/02\\\/06\\\/polizei-kosten-bei-panne-muessen-bezahlt-werden\\\/\"},\"author\":{\"name\":\"maik\",\"@id\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/#\\\/schema\\\/person\\\/4cb59b86ffde81f882f56439688fda19\"},\"headline\":\"Polizei-Kosten bei Panne m\u00fcssen bezahlt werden\",\"datePublished\":\"2010-02-06T08:21:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/2010\\\/02\\\/06\\\/polizei-kosten-bei-panne-muessen-bezahlt-werden\\\/\"},\"wordCount\":115,\"commentCount\":3,\"publisher\":{\"@id\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/#\\\/schema\\\/person\\\/4cb59b86ffde81f882f56439688fda19\"},\"keywords\":[\"Lkw\",\"Panne\",\"Polizei\"],\"articleSection\":[\"Allgemeines\",\"Lkw\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/truckonline.de\\\/blog\\\/2010\\\/02\\\/06\\\/polizei-kosten-bei-panne-muessen-bezahlt-werden\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/2010\\\/02\\\/06\\\/polizei-kosten-bei-panne-muessen-bezahlt-werden\\\/\",\"url\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/2010\\\/02\\\/06\\\/polizei-kosten-bei-panne-muessen-bezahlt-werden\\\/\",\"name\":\"Polizei-Kosten bei Panne m\u00fcssen bezahlt werden | TruckOnline.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/#website\"},\"datePublished\":\"2010-02-06T08:21:52+00:00\",\"description\":\"Wenn die Polizei eine gef\u00e4hrliche Pannenstelle absichert, muss der Eigent\u00fcmer des liegengebliebenen Fahrzeugs die Personalkosten der Beamten \u00fcbernehmen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/2010\\\/02\\\/06\\\/polizei-kosten-bei-panne-muessen-bezahlt-werden\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/truckonline.de\\\/blog\\\/2010\\\/02\\\/06\\\/polizei-kosten-bei-panne-muessen-bezahlt-werden\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/2010\\\/02\\\/06\\\/polizei-kosten-bei-panne-muessen-bezahlt-werden\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Polizei-Kosten bei Panne m\u00fcssen bezahlt werden\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/\",\"name\":\"TruckOnline.de\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/#\\\/schema\\\/person\\\/4cb59b86ffde81f882f56439688fda19\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/#\\\/schema\\\/person\\\/4cb59b86ffde81f882f56439688fda19\",\"name\":\"maik\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/logoinnenweiss.png\",\"url\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/logoinnenweiss.png\",\"contentUrl\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/logoinnenweiss.png\",\"width\":733,\"height\":125,\"caption\":\"maik\"},\"logo\":{\"@id\":\"https:\\\/\\\/truckonline.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/logoinnenweiss.png\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/truckblog\",\"https:\\\/\\\/www.instagram.com\\\/truck_online\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/truckblog\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/truckonline\",\"https:\\\/\\\/www.tumblr.com\\\/truckonline\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Polizei-Kosten bei Panne m\u00fcssen bezahlt werden | TruckOnline.de","description":"Wenn die Polizei eine gef\u00e4hrliche Pannenstelle absichert, muss der Eigent\u00fcmer des liegengebliebenen Fahrzeugs die Personalkosten der Beamten \u00fcbernehmen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/truckonline.de\/blog\/2010\/02\/06\/polizei-kosten-bei-panne-muessen-bezahlt-werden\/","og_locale":"de_DE","og_type":"article","og_title":"Polizei-Kosten bei Panne m\u00fcssen bezahlt werden | TruckOnline.de","og_url":"https:\/\/truckonline.de\/blog\/2010\/02\/06\/polizei-kosten-bei-panne-muessen-bezahlt-werden\/","og_site_name":"TruckOnline.de","article_publisher":"https:\/\/www.facebook.com\/truckblog","article_author":"https:\/\/www.facebook.com\/truckblog","article_published_time":"2010-02-06T08:21:52+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/truckonline.de\/blog\/wp-content\/uploads\/2019\/12\/IMG_20191229_225424-scaled.jpg","type":"image\/jpeg"}],"author":"maik","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/truckblog","twitter_site":"@truckblog","twitter_misc":{"Verfasst von":"maik","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/truckonline.de\/blog\/2010\/02\/06\/polizei-kosten-bei-panne-muessen-bezahlt-werden\/#article","isPartOf":{"@id":"https:\/\/truckonline.de\/blog\/2010\/02\/06\/polizei-kosten-bei-panne-muessen-bezahlt-werden\/"},"author":{"name":"maik","@id":"https:\/\/truckonline.de\/blog\/#\/schema\/person\/4cb59b86ffde81f882f56439688fda19"},"headline":"Polizei-Kosten bei Panne m\u00fcssen bezahlt werden","datePublished":"2010-02-06T08:21:52+00:00","mainEntityOfPage":{"@id":"https:\/\/truckonline.de\/blog\/2010\/02\/06\/polizei-kosten-bei-panne-muessen-bezahlt-werden\/"},"wordCount":115,"commentCount":3,"publisher":{"@id":"https:\/\/truckonline.de\/blog\/#\/schema\/person\/4cb59b86ffde81f882f56439688fda19"},"keywords":["Lkw","Panne","Polizei"],"articleSection":["Allgemeines","Lkw"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/truckonline.de\/blog\/2010\/02\/06\/polizei-kosten-bei-panne-muessen-bezahlt-werden\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/truckonline.de\/blog\/2010\/02\/06\/polizei-kosten-bei-panne-muessen-bezahlt-werden\/","url":"https:\/\/truckonline.de\/blog\/2010\/02\/06\/polizei-kosten-bei-panne-muessen-bezahlt-werden\/","name":"Polizei-Kosten bei Panne m\u00fcssen bezahlt werden | TruckOnline.de","isPartOf":{"@id":"https:\/\/truckonline.de\/blog\/#website"},"datePublished":"2010-02-06T08:21:52+00:00","description":"Wenn die Polizei eine gef\u00e4hrliche Pannenstelle absichert, muss der Eigent\u00fcmer des liegengebliebenen Fahrzeugs die Personalkosten der Beamten \u00fcbernehmen.","breadcrumb":{"@id":"https:\/\/truckonline.de\/blog\/2010\/02\/06\/polizei-kosten-bei-panne-muessen-bezahlt-werden\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/truckonline.de\/blog\/2010\/02\/06\/polizei-kosten-bei-panne-muessen-bezahlt-werden\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/truckonline.de\/blog\/2010\/02\/06\/polizei-kosten-bei-panne-muessen-bezahlt-werden\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/truckonline.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Polizei-Kosten bei Panne m\u00fcssen bezahlt werden"}]},{"@type":"WebSite","@id":"https:\/\/truckonline.de\/blog\/#website","url":"https:\/\/truckonline.de\/blog\/","name":"TruckOnline.de","description":"","publisher":{"@id":"https:\/\/truckonline.de\/blog\/#\/schema\/person\/4cb59b86ffde81f882f56439688fda19"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/truckonline.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/truckonline.de\/blog\/#\/schema\/person\/4cb59b86ffde81f882f56439688fda19","name":"maik","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/truckonline.de\/blog\/wp-content\/uploads\/2019\/12\/logoinnenweiss.png","url":"https:\/\/truckonline.de\/blog\/wp-content\/uploads\/2019\/12\/logoinnenweiss.png","contentUrl":"https:\/\/truckonline.de\/blog\/wp-content\/uploads\/2019\/12\/logoinnenweiss.png","width":733,"height":125,"caption":"maik"},"logo":{"@id":"https:\/\/truckonline.de\/blog\/wp-content\/uploads\/2019\/12\/logoinnenweiss.png"},"sameAs":["https:\/\/www.facebook.com\/truckblog","https:\/\/www.instagram.com\/truck_online\/","https:\/\/x.com\/https:\/\/twitter.com\/truckblog","https:\/\/www.youtube.com\/user\/truckonline","https:\/\/www.tumblr.com\/truckonline"]}]}},"_links":{"self":[{"href":"https:\/\/truckonline.de\/blog\/wp-json\/wp\/v2\/posts\/1186","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/truckonline.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/truckonline.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/truckonline.de\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/truckonline.de\/blog\/wp-json\/wp\/v2\/comments?post=1186"}],"version-history":[{"count":0,"href":"https:\/\/truckonline.de\/blog\/wp-json\/wp\/v2\/posts\/1186\/revisions"}],"wp:attachment":[{"href":"https:\/\/truckonline.de\/blog\/wp-json\/wp\/v2\/media?parent=1186"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/truckonline.de\/blog\/wp-json\/wp\/v2\/categories?post=1186"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/truckonline.de\/blog\/wp-json\/wp\/v2\/tags?post=1186"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}